{"id":10525,"count":1,"description":"","link":"https:\/\/www.travelbymexico.com\/blog\/tag\/festival-internacional-de-cine-de-guadalajara-en-los-angeles\/","name":"Festival Internacional de Cine de Guadalajara en Los Angeles","slug":"festival-internacional-de-cine-de-guadalajara-en-los-angeles","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.travelbymexico.com\/blog\/wp-json\/wp\/v2\/tags\/10525"}],"collection":[{"href":"https:\/\/www.travelbymexico.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.travelbymexico.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.travelbymexico.com\/blog\/wp-json\/wp\/v2\/posts?tags=10525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}